{"id":1174,"date":"2026-03-26T17:09:44","date_gmt":"2026-03-26T16:09:44","guid":{"rendered":"https:\/\/www.biennale-photo-mulhouse.com\/2026en\/?page_id=1174"},"modified":"2026-05-12T13:55:15","modified_gmt":"2026-05-12T11:55:15","slug":"photobook-days","status":"publish","type":"page","link":"https:\/\/www.biennale-photo-mulhouse.com\/2026en\/photobook-days\/","title":{"rendered":"Photobook days"},"content":{"rendered":"<p><strong><span class=\"small\">EN \u2b62 <a href=\"https:\/\/www.biennale-photo-mulhouse.com\/2026\/photobook-days\/\">FR<\/a><\/span><\/strong><\/p>\n<h1><span class=\"theme_color\"><em>PHOTOBOOK DAYS\u00a0<\/em><\/span><\/h1>\n<h2 class=\"cancel_mt\">THE BOOK AS A PHOTOGRAPHIC SPACE<\/h2>\n<p class=\"offsetted\"><strong>Fine Arts Museum, Mulhouse<\/strong><br \/>\n<span class=\"theme_color\"><strong>June 6&amp;7, 2p.m. &#8211; 5 p.m.<\/strong><\/span><\/p>\n<p>As part of its opening days, the festival is hosting two afternoons dedicated to contemporary photography publishing.<\/p>\n<p>The program includes public discussions, lectures, presentations, and book signings that reflect the vitality and diversity of photography publishing.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1182\" src=\"https:\/\/www.biennale-photo-mulhouse.com\/2026en\/wp-content\/uploads\/sites\/9\/2026\/03\/IMG_8071.jpg\" alt=\"\" width=\"1181\" height=\"787\" srcset=\"https:\/\/www.biennale-photo-mulhouse.com\/2026en\/wp-content\/uploads\/sites\/9\/2026\/03\/IMG_8071.jpg 1181w, https:\/\/www.biennale-photo-mulhouse.com\/2026en\/wp-content\/uploads\/sites\/9\/2026\/03\/IMG_8071-768x512.jpg 768w\" sizes=\"auto, (max-width: 1181px) 100vw, 1181px\" \/><\/p>\n<p class=\"img_caption\">George Mahashe, <em>Defunct Context &#8211; Ambivalence to important work<\/em>, 2023<\/p>\n<h2 class=\"offsetted\"><span class=\"theme_color\">Photobook fair<\/span><\/h2>\n<p>During <span class=\"theme_color\"><em>Photobook Days<\/em><\/span>, a photobook fair brings together publishers, bookstores, and artists.<\/p>\n<p><em>With the \u00c9ditions de la Conserverie, XYZ Books, Origini Edizioni, Datz Press, Rue du Bouquet, Orange Claire, L\u2019enfant sauvage, KCR, \u00c9ditions du Ca\u00efd, Filigranes, Loco, Micamera<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1310\" src=\"https:\/\/www.biennale-photo-mulhouse.com\/2026en\/wp-content\/uploads\/sites\/9\/2026\/05\/loco.jpg\" alt=\"\" width=\"2048\" height=\"1152\" srcset=\"https:\/\/www.biennale-photo-mulhouse.com\/2026en\/wp-content\/uploads\/sites\/9\/2026\/05\/loco.jpg 2048w, https:\/\/www.biennale-photo-mulhouse.com\/2026en\/wp-content\/uploads\/sites\/9\/2026\/05\/loco-768x432.jpg 768w, https:\/\/www.biennale-photo-mulhouse.com\/2026en\/wp-content\/uploads\/sites\/9\/2026\/05\/loco-1536x864.jpg 1536w\" sizes=\"auto, (max-width: 2048px) 100vw, 2048px\" \/><\/p>\n<p class=\"img_caption\">\u00a9 \u00c9ditions LOCO<\/p>\n<h2 class=\"offsetted\"><span class=\"theme_color\">Let&rsquo;s talk photobooks<br \/>\n<\/span><em><span class=\"small\">talk and<\/span> <span class=\"small\">conferences<\/span><\/em><\/h2>\n<p class=\"offsetted with_color_diamond\"><span class=\"theme_color\"><strong>Saturday June 6\u00a0<\/strong><\/span><\/p>\n<p class=\"offsetted with_arrow\"><strong>14h30<\/strong>, <span class=\"small\">EN\/FR<\/span> : <span class=\"theme_color\"><em>From Exhibition to Book: Developing a Narrative<\/em><\/span>, talk between Tiago Casanova, photographer and editor of XYZ Books, and Nicolas B\u00e9zard, journalist<\/p>\n<p class=\"offsetted with_arrow\"><strong>15h<\/strong>, <span class=\"small\">EN\/FR<\/span> : \u00a0<span class=\"theme_color\"><em>About Bernard Guillot<\/em><\/span>, talk bewteen Ilias Georgiadis (editor, Origini Edizioni), Patrick Le Bescont (editor Filigranes) and Fabien Ribery (art critic)<\/p>\n<p class=\"offsetted with_arrow\"><strong>16h30<\/strong>,<span class=\"small\"> FR<\/span> : <span class=\"theme_color\"><em>Family Albums, a Different Approach<\/em><\/span> : talk between Pauline Hisbacq (photographer, editor of September books), Fran\u00e7ois Jonquet (photographer) and Fabien Ribery (art critic)<\/p>\n<p class=\"offsetted with_arrow\"><strong>16h30<\/strong>, <span class=\"small\">FR<\/span> : <span class=\"theme_color\"><em>Watching and showing violence<\/em><\/span> : talk between Natalie Malisse, Eleonora Calvelli (photographers) and Nicolas B\u00e9zard (journalist)<\/p>\n<p>&nbsp;<\/p>\n<p class=\"offsetted with_color_diamond\"><span class=\"theme_color\"><strong>Sunday June 7\u00a0<\/strong><\/span><\/p>\n<p class=\"offsetted with_arrow\"><strong>14h30<\/strong>, <span class=\"small\">EN\/FR<\/span>: <span class=\"theme_color\"><em>The Vision Behind Datz Press and Datz Museum:<\/em> <\/span>A Talk by Founder Sangyon Joo<\/p>\n<p class=\"offsetted with_arrow\"><strong>15h<\/strong>, <span class=\"small\">EN<\/span> : <span class=\"theme_color\"><em>I Make Books, Therefore I Am<\/em><\/span>, <span class=\"theme_color\"><em>Jenia Fridlyand about <\/em><em>The Agency<\/em> <\/span>: a talk between the photographer and Giulia Zorzi, bookseller (Micamera)<\/p>\n<p class=\"offsetted with_arrow\"><strong>16h<\/strong>, <span class=\"small\">EN<\/span> : <span class=\"theme_color\"><em>The Italian Photobook 2015\u20132025<\/em><\/span>, lecture by Giulia Zorzi, bookseller (Micamera)\u00a0<\/p>\n<p class=\"offsetted with_arrow\"><strong>16h30<\/strong>, <span class=\"small\">EN\/FR<\/span> : <span class=\"theme_color\"><em>Photographing, Writing, Theorising, <\/em><\/span>a talk between Eric Gyamfi, photographer, Partricia Haynes, art historian and Ange-Fr\u00e9d\u00e9ric Koffi, curator\u00a0<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1181\" src=\"https:\/\/www.biennale-photo-mulhouse.com\/2026en\/wp-content\/uploads\/sites\/9\/2026\/03\/IMG_20240915_150543-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/www.biennale-photo-mulhouse.com\/2026en\/wp-content\/uploads\/sites\/9\/2026\/03\/IMG_20240915_150543-scaled.jpg 2560w, https:\/\/www.biennale-photo-mulhouse.com\/2026en\/wp-content\/uploads\/sites\/9\/2026\/03\/IMG_20240915_150543-768x576.jpg 768w, https:\/\/www.biennale-photo-mulhouse.com\/2026en\/wp-content\/uploads\/sites\/9\/2026\/03\/IMG_20240915_150543-1536x1152.jpg 1536w, https:\/\/www.biennale-photo-mulhouse.com\/2026en\/wp-content\/uploads\/sites\/9\/2026\/03\/IMG_20240915_150543-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/p>\n<p class=\"img_caption\">Lecture by Magali Avezou, BPM 2024<\/p>\n","protected":false},"excerpt":{"rendered":"<p>EN \u2b62 FR PHOTOBOOK DAYS\u00a0 THE BOOK AS A PHOTOGRAPHIC SPACE Fine Arts Museum, Mulhouse June 6&amp;7, 2p.m. &#8211; 5 p.m. As part of its opening days, the festival is hosting two afternoons dedicated to contemporary photography publishing. The program includes public discussions, lectures, presentations, and book signings that reflect the vitality and diversity of [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[1],"class_list":["post-1174","page","type-page","status-publish","hentry","category-non-classe"],"acf":{"photo_gallery":{"gallery":[[{"id":1178,"title":"Photobook days, BPM 2024","caption":"","full_image_url":"https:\/\/www.biennale-photo-mulhouse.com\/2026en\/wp-content\/uploads\/sites\/9\/2026\/03\/Photobook-days-BPM-2024-scaled.jpg","thumbnail_image_url":"https:\/\/www.biennale-photo-mulhouse.com\/2026en\/wp-content\/uploads\/sites\/9\/2026\/03\/Photobook-days-BPM-2024-scaled.jpg","large_srcset":"https:\/\/www.biennale-photo-mulhouse.com\/2026en\/wp-content\/uploads\/sites\/9\/2026\/03\/Photobook-days-BPM-2024-scaled.jpg 2560w, https:\/\/www.biennale-photo-mulhouse.com\/2026en\/wp-content\/uploads\/sites\/9\/2026\/03\/Photobook-days-BPM-2024-768x576.jpg 768w, https:\/\/www.biennale-photo-mulhouse.com\/2026en\/wp-content\/uploads\/sites\/9\/2026\/03\/Photobook-days-BPM-2024-1536x1152.jpg 1536w, https:\/\/www.biennale-photo-mulhouse.com\/2026en\/wp-content\/uploads\/sites\/9\/2026\/03\/Photobook-days-BPM-2024-2048x1536.jpg 2048w","medium_srcset":"https:\/\/www.biennale-photo-mulhouse.com\/2026en\/wp-content\/uploads\/sites\/9\/2026\/03\/Photobook-days-BPM-2024-scaled.jpg 2560w, https:\/\/www.biennale-photo-mulhouse.com\/2026en\/wp-content\/uploads\/sites\/9\/2026\/03\/Photobook-days-BPM-2024-768x576.jpg 768w, https:\/\/www.biennale-photo-mulhouse.com\/2026en\/wp-content\/uploads\/sites\/9\/2026\/03\/Photobook-days-BPM-2024-1536x1152.jpg 1536w, https:\/\/www.biennale-photo-mulhouse.com\/2026en\/wp-content\/uploads\/sites\/9\/2026\/03\/Photobook-days-BPM-2024-2048x1536.jpg 2048w","media_details":{"width":2560,"height":1920,"sizes":{"medium_large":{"file":"Photobook-days-BPM-2024-768x576.jpg","width":768,"height":576,"mime-type":"image\/jpeg","filesize":102819,"source_url":"https:\/\/www.biennale-photo-mulhouse.com\/2026en\/wp-content\/uploads\/sites\/9\/2026\/03\/Photobook-days-BPM-2024-768x576.jpg"},"1536x1536":{"file":"Photobook-days-BPM-2024-1536x1152.jpg","width":1536,"height":1152,"mime-type":"image\/jpeg","filesize":287472,"source_url":"https:\/\/www.biennale-photo-mulhouse.com\/2026en\/wp-content\/uploads\/sites\/9\/2026\/03\/Photobook-days-BPM-2024-1536x1152.jpg"},"2048x2048":{"file":"Photobook-days-BPM-2024-2048x1536.jpg","width":2048,"height":1536,"mime-type":"image\/jpeg","filesize":462780,"source_url":"https:\/\/www.biennale-photo-mulhouse.com\/2026en\/wp-content\/uploads\/sites\/9\/2026\/03\/Photobook-days-BPM-2024-2048x1536.jpg"}}},"alt_text":"","url":"","target":""}]]}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.9.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Photobook days - 2026 Mulhouse Photography Biennial<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.biennale-photo-mulhouse.com\/2026en\/photobook-days\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Photobook days - 2026 Mulhouse Photography Biennial\" \/>\n<meta property=\"og:description\" content=\"EN \u2b62 FR PHOTOBOOK DAYS\u00a0 THE BOOK AS A PHOTOGRAPHIC SPACE Fine Arts Museum, Mulhouse June 6&amp;7, 2p.m. &#8211; 5 p.m. As part of its opening days, the festival is hosting two afternoons dedicated to contemporary photography publishing. The program includes public discussions, lectures, presentations, and book signings that reflect the vitality and diversity of [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.biennale-photo-mulhouse.com\/2026en\/photobook-days\/\" \/>\n<meta property=\"og:site_name\" content=\"2026 Mulhouse Photography Biennial\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/BiennaleDeLaPhotographieDeMulhouse\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T11:55:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.biennale-photo-mulhouse.com\/2026en\/wp-content\/uploads\/sites\/9\/2026\/03\/IMG_8071.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.biennale-photo-mulhouse.com\/2026en\/photobook-days\/\",\"url\":\"https:\/\/www.biennale-photo-mulhouse.com\/2026en\/photobook-days\/\",\"name\":\"Photobook days - 2026 Mulhouse Photography Biennial\",\"isPartOf\":{\"@id\":\"https:\/\/www.biennale-photo-mulhouse.com\/2026en\/#website\"},\"datePublished\":\"2026-03-26T16:09:44+00:00\",\"dateModified\":\"2026-05-12T11:55:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.biennale-photo-mulhouse.com\/2026en\/photobook-days\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.biennale-photo-mulhouse.com\/2026en\/photobook-days\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.biennale-photo-mulhouse.com\/2026en\/photobook-days\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.biennale-photo-mulhouse.com\/2026en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Photobook days\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.biennale-photo-mulhouse.com\/2026en\/#website\",\"url\":\"https:\/\/www.biennale-photo-mulhouse.com\/2026en\/\",\"name\":\"Biennale de la Photographie de Mulhouse\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.biennale-photo-mulhouse.com\/2026en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Photobook days - 2026 Mulhouse Photography Biennial","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.biennale-photo-mulhouse.com\/2026en\/photobook-days\/","og_locale":"fr_FR","og_type":"article","og_title":"Photobook days - 2026 Mulhouse Photography Biennial","og_description":"EN \u2b62 FR PHOTOBOOK DAYS\u00a0 THE BOOK AS A PHOTOGRAPHIC SPACE Fine Arts Museum, Mulhouse June 6&amp;7, 2p.m. &#8211; 5 p.m. As part of its opening days, the festival is hosting two afternoons dedicated to contemporary photography publishing. The program includes public discussions, lectures, presentations, and book signings that reflect the vitality and diversity of [&hellip;]","og_url":"https:\/\/www.biennale-photo-mulhouse.com\/2026en\/photobook-days\/","og_site_name":"2026 Mulhouse Photography Biennial","article_publisher":"https:\/\/www.facebook.com\/BiennaleDeLaPhotographieDeMulhouse","article_modified_time":"2026-05-12T11:55:15+00:00","og_image":[{"url":"https:\/\/www.biennale-photo-mulhouse.com\/2026en\/wp-content\/uploads\/sites\/9\/2026\/03\/IMG_8071.jpg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.biennale-photo-mulhouse.com\/2026en\/photobook-days\/","url":"https:\/\/www.biennale-photo-mulhouse.com\/2026en\/photobook-days\/","name":"Photobook days - 2026 Mulhouse Photography Biennial","isPartOf":{"@id":"https:\/\/www.biennale-photo-mulhouse.com\/2026en\/#website"},"datePublished":"2026-03-26T16:09:44+00:00","dateModified":"2026-05-12T11:55:15+00:00","breadcrumb":{"@id":"https:\/\/www.biennale-photo-mulhouse.com\/2026en\/photobook-days\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.biennale-photo-mulhouse.com\/2026en\/photobook-days\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.biennale-photo-mulhouse.com\/2026en\/photobook-days\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.biennale-photo-mulhouse.com\/2026en\/"},{"@type":"ListItem","position":2,"name":"Photobook days"}]},{"@type":"WebSite","@id":"https:\/\/www.biennale-photo-mulhouse.com\/2026en\/#website","url":"https:\/\/www.biennale-photo-mulhouse.com\/2026en\/","name":"Biennale de la Photographie de Mulhouse","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.biennale-photo-mulhouse.com\/2026en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.biennale-photo-mulhouse.com\/2026en\/wp-json\/wp\/v2\/pages\/1174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biennale-photo-mulhouse.com\/2026en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.biennale-photo-mulhouse.com\/2026en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.biennale-photo-mulhouse.com\/2026en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biennale-photo-mulhouse.com\/2026en\/wp-json\/wp\/v2\/comments?post=1174"}],"version-history":[{"count":10,"href":"https:\/\/www.biennale-photo-mulhouse.com\/2026en\/wp-json\/wp\/v2\/pages\/1174\/revisions"}],"predecessor-version":[{"id":1324,"href":"https:\/\/www.biennale-photo-mulhouse.com\/2026en\/wp-json\/wp\/v2\/pages\/1174\/revisions\/1324"}],"wp:attachment":[{"href":"https:\/\/www.biennale-photo-mulhouse.com\/2026en\/wp-json\/wp\/v2\/media?parent=1174"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biennale-photo-mulhouse.com\/2026en\/wp-json\/wp\/v2\/categories?post=1174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}